{"id":250,"date":"2021-04-29T16:25:04","date_gmt":"2021-04-29T14:25:04","guid":{"rendered":"https:\/\/www.italianaferrometalli.com\/english\/?post_type=portfolio&#038;p=250"},"modified":"2023-07-17T14:29:50","modified_gmt":"2023-07-17T12:29:50","slug":"hot-rolled-pipes-for-low-temperature","status":"publish","type":"portfolio","link":"https:\/\/www.italianaferrometalli.com\/english\/portfolio\/hot-rolled-pipes-for-low-temperature\/","title":{"rendered":"Hot rolled pipes for low temperature"},"content":{"rendered":"<p><a href=\"https:\/\/www.italianaferrometalli.com\/english\/pdf\/Hot-rolled-pipes-low-temperature.pdf\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" alt=\"pdf\" src=\"https:\/\/www.italianaferrometalli.com\/english\/grafica\/scarica-pdf-scheda-tecnica.png\" style=\"margin-right:10px;\" \/>Download the technical sheet of Hot rolled pipes for low temperature ASTM A333 Gr. 1 Gr. 6<\/a><\/p>\n<h2>Supplying conditions<\/h2>\n<ul>\n<li><strong>Manufacturing process<\/strong>: hot finished seamless tubes.<\/li>\n<li><strong>Steel grade<\/strong>: A333 GR.1 \u2013 GR.6<\/li>\n<li><strong>Lenghts<\/strong>: tubes can be supplied in random or fixed lengths according to the standard<\/li>\n<li><strong>Plain ends<\/strong>: tubes can be supplied plain ends.<\/li>\n<li><strong>Tests<\/strong>: every tube is tested according to the standard; hydraulic test or substitutive CND test.<\/li>\n<li><strong>Documents<\/strong>: according to the standard.<\/li>\n<li><strong>Marking<\/strong>: in accordance with the specification.<\/li>\n<li><strong>Surface Treatment<\/strong>: tubes are normally rough supplied. Tubes can be oiled or outside painted.<\/li>\n<li><strong>Packaging<\/strong>: tubes are normally packaged in round bundles with wire tied ends.<\/li>\n<li><strong>Max weight<\/strong>: 2000 kgs. Particular package on request.\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Download the technical sheet of Hot rolled pipes for low temperature ASTM A333 Gr. 1 Gr. 6 Supplying conditions Manufacturing process: hot finished seamless tubes. Steel grade: A333 GR.1 \u2013 GR.6 Lenghts: tubes can be supplied in random or fixed lengths according to the standard Plain ends: tubes can be supplied plain ends. Tests: every [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":316,"parent":0,"menu_order":0,"template":"","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"portfolio-type":[36],"class_list":{"0":"post-250","1":"portfolio","2":"type-portfolio","3":"status-publish","4":"has-post-thumbnail","6":"portfolio-type-tubi-acciaio","7":"entry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hot rolled pipes for low temperature ASTM A333 Gr. 1 Gr. 6<\/title>\n<meta name=\"description\" content=\"Tubes are normally packaged in round bundles with wire tied ends. Max weight: 2000 kgs. Particular package on request\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italianaferrometalli.com\/english\/portfolio\/hot-rolled-pipes-for-low-temperature\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hot rolled pipes for low temperature ASTM A333 Gr. 1 Gr. 6\" \/>\n<meta property=\"og:description\" content=\"Tubes are normally packaged in round bundles with wire tied ends. Max weight: 2000 kgs. Particular package on request\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italianaferrometalli.com\/english\/portfolio\/hot-rolled-pipes-for-low-temperature\/\" \/>\n<meta property=\"og:site_name\" content=\"Italiana Ferro Metalli\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-17T12:29:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italianaferrometalli.com\/english\/wp-content\/uploads\/2021\/04\/fornitura-tubi-lisci-commerciali.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"560\" \/>\n\t<meta property=\"og:image:height\" content=\"373\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italianaferrometalli.com\/english\/portfolio\/hot-rolled-pipes-for-low-temperature\/\",\"url\":\"https:\/\/www.italianaferrometalli.com\/english\/portfolio\/hot-rolled-pipes-for-low-temperature\/\",\"name\":\"Hot rolled pipes for low temperature ASTM A333 Gr. 1 Gr. 6\",\"isPartOf\":{\"@id\":\"https:\/\/www.italianaferrometalli.com\/english\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italianaferrometalli.com\/english\/portfolio\/hot-rolled-pipes-for-low-temperature\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italianaferrometalli.com\/english\/portfolio\/hot-rolled-pipes-for-low-temperature\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italianaferrometalli.com\/english\/wp-content\/uploads\/2021\/04\/fornitura-tubi-lisci-commerciali.jpg\",\"datePublished\":\"2021-04-29T14:25:04+00:00\",\"dateModified\":\"2023-07-17T12:29:50+00:00\",\"description\":\"Tubes are normally packaged in round bundles with wire tied ends. Max weight: 2000 kgs. Particular package on request\",\"breadcrumb\":{\"@id\":\"https:\/\/www.italianaferrometalli.com\/english\/portfolio\/hot-rolled-pipes-for-low-temperature\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italianaferrometalli.com\/english\/portfolio\/hot-rolled-pipes-for-low-temperature\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italianaferrometalli.com\/english\/portfolio\/hot-rolled-pipes-for-low-temperature\/#primaryimage\",\"url\":\"https:\/\/www.italianaferrometalli.com\/english\/wp-content\/uploads\/2021\/04\/fornitura-tubi-lisci-commerciali.jpg\",\"contentUrl\":\"https:\/\/www.italianaferrometalli.com\/english\/wp-content\/uploads\/2021\/04\/fornitura-tubi-lisci-commerciali.jpg\",\"width\":560,\"height\":373,\"caption\":\"Fornitura tubi lisci commerciali\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italianaferrometalli.com\/english\/portfolio\/hot-rolled-pipes-for-low-temperature\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italianaferrometalli.com\/english\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elementi del Portfolio\",\"item\":\"https:\/\/www.italianaferrometalli.com\/english\/portfolio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hot rolled pipes for low temperature\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italianaferrometalli.com\/english\/#website\",\"url\":\"https:\/\/www.italianaferrometalli.com\/english\/\",\"name\":\"Italiana Ferro Metalli\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italianaferrometalli.com\/english\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hot rolled pipes for low temperature ASTM A333 Gr. 1 Gr. 6","description":"Tubes are normally packaged in round bundles with wire tied ends. Max weight: 2000 kgs. Particular package on request","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italianaferrometalli.com\/english\/portfolio\/hot-rolled-pipes-for-low-temperature\/","og_locale":"it_IT","og_type":"article","og_title":"Hot rolled pipes for low temperature ASTM A333 Gr. 1 Gr. 6","og_description":"Tubes are normally packaged in round bundles with wire tied ends. Max weight: 2000 kgs. Particular package on request","og_url":"https:\/\/www.italianaferrometalli.com\/english\/portfolio\/hot-rolled-pipes-for-low-temperature\/","og_site_name":"Italiana Ferro Metalli","article_modified_time":"2023-07-17T12:29:50+00:00","og_image":[{"width":560,"height":373,"url":"https:\/\/www.italianaferrometalli.com\/english\/wp-content\/uploads\/2021\/04\/fornitura-tubi-lisci-commerciali.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italianaferrometalli.com\/english\/portfolio\/hot-rolled-pipes-for-low-temperature\/","url":"https:\/\/www.italianaferrometalli.com\/english\/portfolio\/hot-rolled-pipes-for-low-temperature\/","name":"Hot rolled pipes for low temperature ASTM A333 Gr. 1 Gr. 6","isPartOf":{"@id":"https:\/\/www.italianaferrometalli.com\/english\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italianaferrometalli.com\/english\/portfolio\/hot-rolled-pipes-for-low-temperature\/#primaryimage"},"image":{"@id":"https:\/\/www.italianaferrometalli.com\/english\/portfolio\/hot-rolled-pipes-for-low-temperature\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italianaferrometalli.com\/english\/wp-content\/uploads\/2021\/04\/fornitura-tubi-lisci-commerciali.jpg","datePublished":"2021-04-29T14:25:04+00:00","dateModified":"2023-07-17T12:29:50+00:00","description":"Tubes are normally packaged in round bundles with wire tied ends. Max weight: 2000 kgs. Particular package on request","breadcrumb":{"@id":"https:\/\/www.italianaferrometalli.com\/english\/portfolio\/hot-rolled-pipes-for-low-temperature\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italianaferrometalli.com\/english\/portfolio\/hot-rolled-pipes-for-low-temperature\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italianaferrometalli.com\/english\/portfolio\/hot-rolled-pipes-for-low-temperature\/#primaryimage","url":"https:\/\/www.italianaferrometalli.com\/english\/wp-content\/uploads\/2021\/04\/fornitura-tubi-lisci-commerciali.jpg","contentUrl":"https:\/\/www.italianaferrometalli.com\/english\/wp-content\/uploads\/2021\/04\/fornitura-tubi-lisci-commerciali.jpg","width":560,"height":373,"caption":"Fornitura tubi lisci commerciali"},{"@type":"BreadcrumbList","@id":"https:\/\/www.italianaferrometalli.com\/english\/portfolio\/hot-rolled-pipes-for-low-temperature\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italianaferrometalli.com\/english\/"},{"@type":"ListItem","position":2,"name":"Elementi del Portfolio","item":"https:\/\/www.italianaferrometalli.com\/english\/portfolio\/"},{"@type":"ListItem","position":3,"name":"Hot rolled pipes for low temperature"}]},{"@type":"WebSite","@id":"https:\/\/www.italianaferrometalli.com\/english\/#website","url":"https:\/\/www.italianaferrometalli.com\/english\/","name":"Italiana Ferro Metalli","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italianaferrometalli.com\/english\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.italianaferrometalli.com\/english\/wp-json\/wp\/v2\/portfolio\/250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.italianaferrometalli.com\/english\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.italianaferrometalli.com\/english\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.italianaferrometalli.com\/english\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":7,"href":"https:\/\/www.italianaferrometalli.com\/english\/wp-json\/wp\/v2\/portfolio\/250\/revisions"}],"predecessor-version":[{"id":375,"href":"https:\/\/www.italianaferrometalli.com\/english\/wp-json\/wp\/v2\/portfolio\/250\/revisions\/375"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italianaferrometalli.com\/english\/wp-json\/wp\/v2\/media\/316"}],"wp:attachment":[{"href":"https:\/\/www.italianaferrometalli.com\/english\/wp-json\/wp\/v2\/media?parent=250"}],"wp:term":[{"taxonomy":"portfolio-type","embeddable":true,"href":"https:\/\/www.italianaferrometalli.com\/english\/wp-json\/wp\/v2\/portfolio-type?post=250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}